{"id":4626,"date":"2021-05-26T12:25:36","date_gmt":"2021-05-26T10:25:36","guid":{"rendered":"https:\/\/www.bastel-bastel.de\/blog\/?p=4626"},"modified":"2021-05-26T12:25:36","modified_gmt":"2021-05-26T10:25:36","slug":"jochens-wetterblog-am-27-5-2021","status":"publish","type":"post","link":"https:\/\/www.bastel-bastel.de\/blog\/index.php\/2021\/05\/26\/jochens-wetterblog-am-27-5-2021\/","title":{"rendered":"Jochens Wetterblog am 27.5.2021"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/www.bastel-bastel.de\/blog\/wp-content\/uploads\/2021\/05\/DSC00148-682x1024.jpg\" alt=\"\" class=\"wp-image-4627\" srcset=\"https:\/\/www.bastel-bastel.de\/blog\/wp-content\/uploads\/2021\/05\/DSC00148-682x1024.jpg 682w, https:\/\/www.bastel-bastel.de\/blog\/wp-content\/uploads\/2021\/05\/DSC00148-200x300.jpg 200w, https:\/\/www.bastel-bastel.de\/blog\/wp-content\/uploads\/2021\/05\/DSC00148-768x1152.jpg 768w, https:\/\/www.bastel-bastel.de\/blog\/wp-content\/uploads\/2021\/05\/DSC00148-1024x1536.jpg 1024w, https:\/\/www.bastel-bastel.de\/blog\/wp-content\/uploads\/2021\/05\/DSC00148.jpg 1333w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n\n\n<p><strong>R\u00fcckblick<\/strong><br>Das Wetter zeigte sich letzte Woche deutlich weniger dramatisch, als von den Wetterdiensten vorhergesagt. Statt Dauerregen gab es insgesamt nur knapp 3l\/qm Niederschlag. Der Wind blies aber dauerhaft und war die ganze Woche deutlich zu sp\u00fcren. In B\u00f6en wurden bis \u00fcber 58km\/h erreicht. Die Temperaturen bewegten sich weiter auf April-Niveau. Die 20\u00b0C-Marke wurde nur am Montag \u00fcberschritten. An den anderen Tagen blieben die Werte knapp darunter. Nachts k\u00fchlte es auf 5\u00b0C bis 9\u00b0C ab. Durch den vielen Wind bewegten sich die Wolken sehr rasch und es gab einen dauernden Wechsel zwischen dichter Bew\u00f6lkung und Sonnenschein. Am Freitag kam die Sonne kaum durch die Wolken, an den anderen Tagen reichte es jeweils zu einer Sonnenscheindauer zwischen 4 und 7 Stunden. Am Wochenende war das Wetter trocken genug f\u00fcr Outdoor-Aktivit\u00e4ten. Beim Radfahren gab es aber oft deutlichen Gegenwind. Der Mai bleibt weiter zu kalt und trotz der vielen Wolken fehlt noch einiger Niederschlag bis das Monats-Soll erf\u00fcllt ist.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Ausblick<\/strong><\/p>\n\n\n\n<p>Die Wolken bleiben uns bis Freitag erhalten, ab Samstag k\u00e4mpft sich dann immer wieder die Sonne durch. Die Temperaturen steigen tags\u00fcber bis 17\u00b0C, nachts k\u00fchlt es auf Werte um 7\u00b0c ab. 20\u00b0C werden aber wohl erst am Montag erreicht. Die Langfristvorhersage ist oft sehr ungenau, aber ab Ende n\u00e4chster Woche k\u00f6nnte der Sommer vorbeischauen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00fcckblickDas Wetter zeigte sich letzte Woche deutlich weniger dramatisch, als von den Wetterdiensten vorhergesagt. Statt Dauerregen gab es insgesamt nur<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-4626","post","type-post","status-publish","format-standard","hentry","category-wetter-der-blog-zu-www-ingersheimwetter-de"],"_links":{"self":[{"href":"https:\/\/www.bastel-bastel.de\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bastel-bastel.de\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bastel-bastel.de\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bastel-bastel.de\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bastel-bastel.de\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=4626"}],"version-history":[{"count":1,"href":"https:\/\/www.bastel-bastel.de\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4626\/revisions"}],"predecessor-version":[{"id":4628,"href":"https:\/\/www.bastel-bastel.de\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4626\/revisions\/4628"}],"wp:attachment":[{"href":"https:\/\/www.bastel-bastel.de\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=4626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bastel-bastel.de\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=4626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bastel-bastel.de\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=4626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}